{"text_format":"1","workbook":"xlsx","n_sheets":9,"sheets":["Overview","Sheet Validation","1. Staff costs","2-3. Travel Costs&Costs of Stay","4. Equipment Costs","5. Subcontracting Costs","Co-financing","Breakdown & Project Funding","Unit Costs & Funding Rule"],"not_rendered":{"charts":0,"images":2,"macros":1,"external_links":0,"defined_names":39,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Overview","index":0,"n_rows":80,"n_cols":11,"rows_kept":80,"cut":false,"hidden":false,"merged":[[23,1,23,10],[17,1,17,2],[18,1,18,2],[19,1,19,2],[20,1,20,2],[21,1,21,2],[20,4,20,7],[20,8,20,10],[21,4,21,7],[21,8,21,10],[17,4,17,7],[18,4,18,7],[19,4,19,7],[19,8,19,10],[18,8,18,10],[17,8,17,10],[6,1,6,10],[7,1,7,10],[8,1,8,10],[10,1,10,2],[11,1,11,2],[10,4,10,10],[12,1,12,2],[15,1,15,10],[16,1,16,2],[12,4,12,10],[11,4,11,10],[13,1,13,2],[13,3,13,10],[16,8,16,10],[16,4,16,7]]}
[]
[]
[null,null,null,"Key Action 2: Cooperation for innovation and the exchange of good practices"]
[null,null,null,"Capacity Building in the field of higher education"]
[]
[]
[null,"Before completing this table please read carefully the instructions available on the EACEA website"]
[null,"CALL FOR PROPOSALS 2018 – EAC/A05/2017 - Erasmus+ Programme (2017/C 361/04)"]
[null,"Programme guide and instructions for applicants"]
[]
[null,"Action",null,null,{"$f":"IF(D11=\"\",\"Please select Action Type\",IF(OR(D11=\"Joint Project\",D11=\"Structural Project\"),\"\",\"Error Type of Action\"))","v":"Please select Action Type"}]
[null,"Duration number of months",null,null,{"$f":"IF(D12=\"\",\"Please select duration\",IF(OR(D12=24,D12=36),\"\",\"Error duration\"))","v":"Please select duration"}]
[null,"Project Acronym",null,null,{"$f":"IF(D13=\"\",\"Please fill in Project Acronym\",\"\")","v":"Please fill in Project Acronym"}]
[null,"Project Title"]
[]
[null,"EU GRANT REQUESTED FROM THE EUROPEAN UNION (in EUR)"]
[null,"1. Staff Costs",null,{"$f":"'1. Staff costs'!D9","v":0},{"$f":"\"Cannot exceed 40% of total Grant requested\"","v":"Cannot exceed 40% of total Grant requested"},null,null,null,{"$f":"IF(COUNTIF('1. Staff costs'!T:T,\"Error\")<=1,\"\",\"Please check data in Tab '1. Staff Costs'\")","v":"Please check data in Tab '1. Staff Costs'"}]
[null,"2. Travel Costs + Exceptional Travel Costs",null,{"$f":"'2-3. Travel Costs&Costs of Stay'!D8+IF(OR(C26=\"\",D26=\"\"),0,'2-3. Travel Costs&Costs of Stay'!J4)","v":0},{"$f":"IF(AND('2-3. Travel Costs&Costs of Stay'!D8=0,'2-3. Travel Costs&Costs of Stay'!J4>0),\"Exceptional travel costs exceed 80% of total travel costs\",IFERROR(IF('2-3. Travel Costs&Costs of Stay'!J4/'2-3. Travel Costs&Costs of Stay'!D8>0.8,\"Exceptional travel costs exceed 80% of total travel costs\",\"\"),\"\"))","v":""},null,null,null,{"$f":"IF(COUNTIF('2-3. Travel Costs&Costs of Stay'!O:O,\"Error\")<=1,\"\",\"Please check data in Tab '2-3. Travel Costs&Costs of Stay'\")","v":"Please check data in Tab '2-3. Travel Costs&Costs of Stay'"}]
[null,"3. Costs of Stay",null,{"$f":"'2-3. Travel Costs&Costs of Stay'!D9","v":0},null,null,null,null,{"$f":"IF(COUNTIF('2-3. Travel Costs&Costs of Stay'!O:O,\"Error\")<=1,\"\",\"Please check data in Tab '2-3. Travel Costs&Costs of Stay'\")","v":"Please check data in Tab '2-3. Travel Costs&Costs of Stay'"}]
[null,"4. Equipment Costs",null,{"$f":"'4. Equipment Costs'!C4","v":0},{"$f":"\"Cannot exceed 30% of Total Grant requested\"","v":"Cannot exceed 30% of Total Grant requested"},null,null,null,{"$f":"IF(COUNTIF('4. Equipment Costs'!I:T,\"Error\")<=1,\"\",\"Please check data in Tab '4. Equipment Costs''\")","v":"Please check data in Tab '4. Equipment Costs''"}]
[null,"5. Subcontracting Costs",null,{"$f":"'5. Subcontracting Costs'!C4","v":0},{"$f":"\"Cannot exceed 10% of Total Grant requested\"","v":"Cannot exceed 10% of Total Grant requested"},null,null,null,{"$f":"IF(COUNTIF('5. Subcontracting Costs'!I:I,\"Error\")<=1,\"\",\"Please check data in Tab '5. Subcontracting Costs'\")","v":"Please check data in Tab '5. Subcontracting Costs'"}]
[null,"Total Grant requested from the European Union",null,{"$f":"SUM(D17:D21)","v":0},{"$f":"\"Should be equal or above EUR 500.000,00 and cannot exceed EUR 1.000.000,00\"","v":"Should be equal or above EUR 500.000,00 and cannot exceed EUR 1.000.000,00"},null,null,null,{"$f":"IF(OR(COUNTIF('Co-financing'!J:J,\"Error\")<=1,AND('Co-financing'!B14=\"\",'Co-financing'!E14=\"\",'Co-financing'!F14=\"\",'Co-financing'!G14=\"\",'Co-financing'!H14=0)),\"\",\"Please check data in Tab 'Co-financing'\")","v":""}]
[]
[null,"DISTRIBUTION OF THE GRANT BY ORGANISATION (in EUR)"]
[null,"Partner \nN°","Name of Partner","Country","PR/PA","1. Staff \nCosts","2. Travel \nCosts","3. Costs of \nStay","4. Equipment \nCosts","5. Subcontracting \nCosts","Total \nCosts (in EUR)"]
[null,"P1",null,null,{"$f":"IFERROR(IF(D26<>\"\",VLOOKUP(D26,CountryType,2,FALSE),\"\"),\"Country not found\")","v":""},{"$f":"SUMIF('1. Staff costs'!C:C,B26,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B26,'2-3. Travel Costs&Costs of Stay'!L:L)+IF(OR(C26=\"\",D26=\"\"),0,'2-3. Travel Costs&Costs of Stay'!J4)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B26,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B26,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B26,'5. Subcontracting Costs'!H:H)","v":0},{"$f":"IF(OR(C26=\"\",D26=\"\"),0,SUM(F26:J26))","v":0}]
[null,"P2",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B27,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B27,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B27,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B27,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B27,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P3",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B28,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B28,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B28,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B28,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B28,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P4",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B29,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B29,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B29,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B29,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B29,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P5",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B30,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B30,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B30,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B30,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B30,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P6",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B31,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B31,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B31,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B31,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B31,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P7",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B32,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B32,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B32,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B32,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B32,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P8",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B33,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B33,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B33,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B33,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B33,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P9",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B34,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B34,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B34,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B34,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B34,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P10",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B35,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B35,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B35,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B35,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B35,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P11",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B36,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B36,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B36,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B36,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B36,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P12",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B37,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B37,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B37,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B37,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B37,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P13",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B38,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B38,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B38,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B38,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B38,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P14",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B39,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B39,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B39,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B39,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B39,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P15",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B40,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B40,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B40,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B40,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B40,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P16",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B41,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B41,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B41,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B41,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B41,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P17",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B42,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B42,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B42,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B42,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B42,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P18",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B43,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B43,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B43,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B43,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B43,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P19",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B44,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B44,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B44,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B44,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B44,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P20",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B45,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B45,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B45,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B45,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B45,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P21",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B46,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B46,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B46,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B46,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B46,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P22",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B47,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B47,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B47,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B47,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B47,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P23",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B48,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B48,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B48,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B48,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B48,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P24",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B49,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B49,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B49,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B49,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B49,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P25",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B50,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B50,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B50,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B50,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B50,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P26",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B51,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B51,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B51,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B51,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B51,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P27",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B52,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B52,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B52,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B52,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B52,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P28",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B53,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B53,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B53,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B53,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B53,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P29",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B54,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B54,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B54,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B54,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B54,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P30",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B55,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B55,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B55,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B55,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B55,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P31",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B56,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B56,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B56,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B56,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B56,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P32",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B57,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B57,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B57,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B57,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B57,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P33",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B58,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B58,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B58,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B58,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B58,'5. Subcontracting Costs'!H:H)","v":0},{"$f":"IF(OR(C58=\"\",D58=\"\"),0,SUM(F58:J58))","v":0}]
[null,"P34",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B59,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B59,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B59,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B59,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B59,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P35",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B60,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B60,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B60,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B60,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B60,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P36",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B61,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B61,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B61,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B61,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B61,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P37",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B62,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B62,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B62,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B62,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B62,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P38",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B63,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B63,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B63,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B63,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B63,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P39",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B64,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B64,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B64,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B64,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B64,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P40",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B65,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B65,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B65,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B65,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B65,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P41",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B66,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B66,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B66,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B66,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B66,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P42",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B67,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B67,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B67,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B67,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B67,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P43",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B68,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B68,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B68,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B68,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B68,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P44",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B69,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B69,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B69,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B69,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B69,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P45",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B70,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B70,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B70,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B70,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B70,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P46",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B71,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B71,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B71,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B71,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B71,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P47",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B72,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B72,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B72,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B72,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B72,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P48",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B73,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B73,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B73,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B73,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B73,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P49",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B74,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B74,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B74,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B74,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B74,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P50",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B75,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B75,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B75,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B75,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B75,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P51",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B76,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B76,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B76,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B76,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B76,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P52",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B77,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B77,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B77,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B77,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B77,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P53",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B78,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B78,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B78,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B78,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B78,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P54",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B79,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B79,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B79,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B79,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B79,'5. Subcontracting Costs'!H:H)","v":0},0]
[null,"P55",null,null,"",{"$f":"SUMIF('1. Staff costs'!C:C,B80,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B80,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!C:C,B80,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!C:C,B80,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!C:C,B80,'5. Subcontracting Costs'!H:H)","v":0},0]

{"sheet":"Sheet Validation","index":1,"n_rows":7,"n_cols":2,"rows_kept":7,"cut":false,"hidden":true,"merged":[]}
["Data Sheet Validation"]
["1. Staff Costs",{"$f":"IF(COUNTIF('1. Staff costs'!T:T,\"Error\")<=1,\"OK\",\"Please check data in Tab '\"&A2&\"'\")","v":"Please check data in Tab '1. Staff Costs'"}]
["2-3. Travel Costs&Costs of Stay",{"$f":"IF(COUNTIF('2-3. Travel Costs&Costs of Stay'!O:O,\"Error\")<=1,\"OK\",\"Please check data in Tab '\"&A3&\"'\")","v":"Please check data in Tab '2-3. Travel Costs&Costs of Stay'"}]
["4. Equipment Costs",{"$f":"IF(COUNTIF('4. Equipment Costs'!I:T,\"Error\")<=1,\"OK\",\"Please check data in Tab '\"&A4&\"'\")","v":"Please check data in Tab '4. Equipment Costs'"}]
["5. Subcontracting Costs",{"$f":"IF(COUNTIF('5. Subcontracting Costs'!I:I,\"Error\")<=1,\"OK\",\"Please check data in Tab '\"&A5&\"'\")","v":"Please check data in Tab '5. Subcontracting Costs'"}]
["Co-financing",{"$f":"IF(COUNTIF('Co-financing'!J:J,\"Error\")<=1,\"OK\",\"Please check data in Tab '\"&A6&\"'\")","v":"Please check data in Tab 'Co-financing'"}]
["Exceptional Travel Costs (EUR)",{"$f":"IF('2-3. Travel Costs&Costs of Stay'!K4=\"\",\"OK\",\"Please check Exceptional Travel Costs (EUR) in Tab '\"&A3&\"'\")","v":"OK"}]

{"sheet":"1. Staff costs","index":2,"n_rows":14,"n_cols":20,"rows_kept":14,"cut":false,"hidden":false,"merged":[[1,1,1,19],[10,18,11,18],[10,5,10,7],[10,8,10,10],[10,11,10,13],[10,14,10,16],[10,1,11,1],[10,4,11,4],[10,3,11,3],[10,2,11,2],[7,1,7,2],[6,1,6,2],[5,1,5,2],[4,1,4,2],[3,1,3,2],[8,1,8,2],[10,17,11,17],[3,5,8,19],[9,1,9,19],[2,1,2,19],[10,19,11,19]]}
[]
[null,"1. Staff Costs"]
[]
[null,null,null,"Total (EUR)","Number of Days"]
[null,"Manager",null,{"$f":"SUM(H:H)","v":0},{"$f":"SUMIF(T:T,\"<>Error\",F:F)","v":0}]
[null,"Teacher/Trainer/Researcher",null,{"$f":"SUM(K:K)","v":0},{"$f":"SUMIF(T:T,\"<>Error\",I:I)","v":0}]
[null,"Technical Staff",null,{"$f":"SUM(N:N)","v":0},{"$f":"SUMIF(T:T,\"<>Error\",L:L)","v":0}]
[null,"Administrative Staff",null,{"$f":"SUM(Q:Q)","v":0},{"$f":"SUMIF(T:T,\"<>Error\",O:O)","v":0}]
[null,null,null,{"$f":"SUM(D5:D8)","v":0},{"$f":"SUM(E5:E8)","v":0}]
[]
[null,"Work\nPackage","Partner \nN°","Name of Partner\n(to encode in overview sheet)","Country\n(to encode in overview sheet)",{"$f":"'Unit Costs & Funding Rule'!D7","v":"Manager"},null,null,{"$f":"'Unit Costs & Funding Rule'!E7","v":"Teacher/Trainer/Researcher"},null,null,{"$f":"'Unit Costs & Funding Rule'!F7","v":"Technical Staff"},null,null,{"$f":"'Unit Costs & Funding Rule'!G7","v":"Administrative Staff"},null,null,"Total Number \nof Days","Total \n(EUR)","Check\nData\nEncoding"]
[null,null,null,null,null,"Number of \ndays","Unit cost \nper day","Total\n(EUR)","Number of \ndays","Unit cost \nper day","Total\n(EUR)","Number of \ndays","Unit cost \nper day","Total\n(EUR)","Number of \ndays","Unit cost \nper day","Total\n(EUR)"]
[null,null,null,{"$f":"IFERROR(IF(VLOOKUP(C13,PartnerN°Ref,2,FALSE)=0,\"\",VLOOKUP(C13,PartnerN°Ref,2,FALSE)),\"\")","v":""},{"$f":"IFERROR(IF(OR(VLOOKUP(C13,PartnerN°Ref,4,FALSE)=\"Country not found\",VLOOKUP(C13,PartnerN°Ref,3,FALSE)=0),\"\",VLOOKUP(C13,PartnerN°Ref,3,FALSE)),\"\")","v":""},0,{"$f":"IF(T13=\"Error\",0,INDEX(Rates,MATCH(E13,CountryALL,0),MATCH($F$11,Category,0)))","v":0},{"$f":"IFERROR(IF(T13=\"Error\",0,ROUND(F13*G13,2)),0)","v":0},0,{"$f":"IF(T13=\"Error\",0,INDEX(Rates,MATCH(E13,CountryALL,0),MATCH($I$11,Category,0)))","v":0},{"$f":"IFERROR(IF(T13=\"Error\",0,ROUND(I13*J13,2)),0)","v":0},0,{"$f":"IF(T13=\"Error\",0,INDEX(Rates,MATCH(E13,CountryALL,0),MATCH($L$11,Category,0)))","v":0},{"$f":"IFERROR(IF(T13=\"Error\",0,ROUND(L13*M13,2)),0)","v":0},0,{"$f":"IF(T13=\"Error\",0,INDEX(Rates,MATCH(E13,CountryALL,0),MATCH($O$11,Category,0)))","v":0},{"$f":"IFERROR(IF(T13=\"Error\",0,ROUND(O13*P13,2)),0)","v":0},{"$f":"IF(T13=\"Error\",0,F13+I13+L13+O13)","v":0},{"$f":"IF(T13=\"Error\",0,H13+K13+N13+Q13)","v":0},{"$f":"IF(OR(COUNTIF(WorkPackage,B13)=0,COUNTIF(PartnerN°,C13)=0,D13=\"\",COUNTIF(CountryALL,E13)=0,ISNUMBER(F13)=FALSE,ISNUMBER(I13)=FALSE,ISNUMBER(L13)=FALSE,ISNUMBER(O13)=FALSE,IF(ISNUMBER(F13)=TRUE,F13=INT(F13*10)/10=FALSE),IF(ISNUMBER(I13)=TRUE,I13=INT(I13*10)/10=FALSE),IF(ISNUMBER(L13)=TRUE,L13=INT(L13*10)/10=FALSE),IF(ISNUMBER(O13)=TRUE,O13=INT(O13*10)/10=FALSE)),\"Error\",\"\")","v":"Error"}]
[null,null,null,"","",0,0,0,0,0,0,0,0,0,0,0,0,0,0,"Error"]

{"sheet":"2-3. Travel Costs&Costs of Stay","index":3,"n_rows":14,"n_cols":15,"rows_kept":14,"cut":false,"hidden":false,"merged":[[5,7,5,9],[2,1,2,14],[7,4,8,4],[5,4,6,4],[3,4,4,4],[5,1,5,2],[4,1,4,2],[3,1,3,2],[3,7,3,8],[3,10,3,13],[10,2,11,2],[8,1,8,2],[7,1,7,2],[6,1,6,2],[9,1,9,14],[10,14,11,14],[6,7,8,9],[1,1,1,14],[10,5,11,5],[10,8,11,8],[10,7,11,7],[10,6,11,6],[10,4,11,4],[10,3,11,3],[10,13,11,13],[10,12,11,12],[10,11,11,11],[10,10,11,10],[10,9,11,9],[7,5,8,5],[5,5,6,5],[3,5,4,5],[10,1,11,1]]}
[]
[null,"2-3. Travel Costs & Costs of Stay"]
[]
[null,"Travel Costs Student (EUR)",null,{"$f":"SUMIF(G:G,\"Student\",L:L)","v":0},{"$f":"D4+D5","v":0},{"$f":"SUMIFS(H:H,G:G,\"Student\",O:O,\"<>Error\")","v":0},null,"Exceptional Travel Costs (EUR)",null,null,{"$f":"IF(AND(D8=0,J4>0),\"EXCEEDING 80% OF TOTAL TRAVEL COSTS\",IFERROR(IF(J4/D8>0.8,\"EXCEEDING 80% OF TOTAL TRAVEL COSTS\",\"\"),\"\"))","v":""}]
[null,"Costs of Stay Student (EUR)",null,{"$f":"SUMIF(G:G,\"Student\",M:M)","v":0}]
[null,"Travel Costs Staff (EUR)",null,{"$f":"SUMIF(G:G,\"Staff\",L:L)","v":0},{"$f":"D6+D7","v":0},{"$f":"SUMIFS(H:H,G:G,\"Staff\",O:O,\"<>Error\")","v":0},null,"Exceptional Travel Costs\nPlease encode here above the estimated amount for exceptional travel costs. Please note that this amount will be added to the amount of travel costs forectasted for the Partner n°1"]
[null,"Costs of Stay Staff (EUR)",null,{"$f":"SUMIF(G:G,\"Staff\",M:M)","v":0},null,null,null,"Please encode here above the estimated amount for exceptional travel costs. Please note that this amount will be added to the amount of travel costs of the Partner n°1."]
[null,"Total Travel Costs (EUR)",null,{"$f":"SUM(L:L)","v":0},{"$f":"D8+D9","v":0},{"$f":"F4+F6","v":0}]
[null,"Total Costs of Stay (EUR)",null,{"$f":"SUM(M:M)","v":0}]
[]
[null,"Work\nPackage","Partner \nN°","Name of Partner\n(to encode in overview sheet)","Country\n(to encode in overview sheet)","City of Departure","Student/\nStaff","Number of \nParticipants","City of Destination","Travel Distance","Number of \ndays (per participant)","Travel \nCosts\n(EUR)","Costs of\nStay\n(EUR)","Total \n(EUR)","Check\nData\nEncoding"]
[]
[null,null,null,{"$f":"IFERROR(IF(VLOOKUP(C13,PartnerN°Ref,2,FALSE)=0,\"\",VLOOKUP(C13,PartnerN°Ref,2,FALSE)),\"\")","v":""},{"$f":"IFERROR(IF(OR(VLOOKUP(C13,PartnerN°Ref,4,FALSE)=\"Country not found\",VLOOKUP(C13,PartnerN°Ref,3,FALSE)=0),\"\",VLOOKUP(C13,PartnerN°Ref,3,FALSE)),\"\")","v":""},null,null,0,null,null,0,{"$f":"IF(O13=\"Error\",0,ROUND(ROUND(H13,0)*(VLOOKUP(J13,TravelCosts,2,FALSE)),2))","v":0},{"$f":"IF(O13=\"Error\",0,IF(AND(G13=\"Staff\",K13>0,K13<15),(120*K13)*H13,IF(AND(G13=\"Staff\",K13>14,K13<61),(1680+((K13-14)*70))*H13,IF(AND(G13=\"Staff\",K13>60,K13<91),(4900+((K13-60)*50))*H13,IF(AND(G13=\"Student\",K13>0,K13<15),(55*K13)*H13,IF(AND(G13=\"Student\",K13>14,K13<91),(770+((K13-14)*40))*H13,0))))))","v":0},{"$f":"L13+M13","v":0},{"$f":"IF(OR(COUNTIF(WorkPackage,B13)=0,COUNTIF(PartnerN°,C13)=0,D13=\"\",COUNTIF(CountryALL,E13)=0,F13=\"\",COUNTIF(Category2,G13)=0,ISNUMBER(H13)=FALSE,H13<=0,I13=\"\",COUNTIF(TravelBands,J13)=0,ISNUMBER(K13)=FALSE,OR(K13<0,K13>90),IF(ISNUMBER(H13)=TRUE,H13=INT(H13*1)/1=FALSE),IF(ISNUMBER(K13)=TRUE,K13=INT(K13*1)/1=FALSE)),\"Error\",\"\")","v":"Error"}]
[null,null,null,"","",null,null,0,null,null,0,0,0,{"$f":"L14+M14","v":0},{"$f":"IF(OR(COUNTIF(WorkPackage,B14)=0,COUNTIF(PartnerN°,C14)=0,D14=\"\",COUNTIF(CountryALL,E14)=0,F14=\"\",COUNTIF(Category2,G14)=0,ISNUMBER(H14)=FALSE,H14<=0,I14=\"\",COUNTIF(TravelBands,J14)=0,ISNUMBER(K14)=FALSE,OR(K14<0,K14>90),IF(ISNUMBER(H14)=TRUE,H14=INT(H14*1)/1=FALSE),IF(ISNUMBER(K14)=TRUE,K14=INT(K14*1)/1=FALSE)),\"Error\",\"\")","v":"Error"}]

{"sheet":"4. Equipment Costs","index":4,"n_rows":14,"n_cols":9,"rows_kept":14,"cut":false,"hidden":false,"merged":[[0,1,0,8],[2,1,2,8],[9,1,9,8],[3,4,8,8],[10,8,11,8],[1,1,1,8],[10,7,11,7],[10,6,11,6],[10,5,11,5],[10,4,11,4],[3,1,8,1],[3,2,8,3],[10,3,11,3],[10,1,11,1],[10,2,11,2]]}
[]
[null,"4. Equipment Costs"]
[]
[null,"Total (EUR)",{"$f":"SUM(H:H)","v":0}]
[]
[]
[]
[]
[]
[]
[null,"Work\nPackage","Partner \nN°","Name of Partner\n(to encode in overview sheet)","Country\n(to encode in overview sheet)","Nature, type and specifications of the item","Amount\nExcluding VAT\n(EUR)","Total\n(EUR)","Check\nData\nEncoding"]
[]
[null,null,null,{"$f":"IFERROR(IF(VLOOKUP(C13,PartnerN°Ref,2,FALSE)=0,\"\",VLOOKUP(C13,PartnerN°Ref,2,FALSE)),\"\")","v":""},{"$f":"IFERROR(IF(OR(VLOOKUP(C13,PartnerN°Ref,4,FALSE)=\"Country not found\",VLOOKUP(C13,PartnerN°Ref,3,FALSE)=0),\"\",VLOOKUP(C13,PartnerN°Ref,3,FALSE)),\"\")","v":""},null,0,{"$f":"IF(I13=\"Error\",0,ROUND(G13,2))","v":0},{"$f":"IF(OR(COUNTIF(WorkPackage,B13)=0,COUNTIF(PartnerN°,C13)=0,D13=\"\",COUNTIF(CountryEligEquip,E13)=0,F13=\"\",ISNUMBER(G13)=FALSE,IF(ISNUMBER(G13)=TRUE,G13=INT(G13*100)/100=FALSE)),\"Error\",\"\")","v":"Error"}]
[null,null,null,{"$f":"IFERROR(IF(VLOOKUP(C14,PartnerN°Ref,2,FALSE)=0,\"\",VLOOKUP(C14,PartnerN°Ref,2,FALSE)),\"\")","v":""},{"$f":"IFERROR(IF(OR(VLOOKUP(C14,PartnerN°Ref,4,FALSE)=\"Country not found\",VLOOKUP(C14,PartnerN°Ref,3,FALSE)=0),\"\",VLOOKUP(C14,PartnerN°Ref,3,FALSE)),\"\")","v":""},null,0,{"$f":"IF(I14=\"Error\",0,ROUND(G14,2))","v":0},{"$f":"IF(OR(COUNTIF(WorkPackage,B14)=0,COUNTIF(PartnerN°,C14)=0,D14=\"\",COUNTIF(CountryEligEquip,E14)=0,F14=\"\",ISNUMBER(G14)=FALSE,IF(ISNUMBER(G14)=TRUE,G14=INT(G14*100)/100=FALSE)),\"Error\",\"\")","v":"Error"}]

{"sheet":"5. Subcontracting Costs","index":5,"n_rows":14,"n_cols":9,"rows_kept":14,"cut":false,"hidden":false,"merged":[[0,1,0,8],[10,8,11,8],[1,1,1,8],[10,7,11,7],[3,1,8,1],[3,2,8,3],[10,1,11,1],[10,2,11,2],[10,3,11,3],[10,4,11,4],[10,5,11,5],[10,6,11,6],[3,4,8,8],[2,1,2,8],[9,1,9,8]]}
[]
[null,"5. Subcontracting Costs"]
[]
[null,"Total (EUR)",{"$f":"SUM(H:H)","v":0}]
[]
[]
[]
[]
[]
[]
[null,"Work\nPackage","Partner \nN°","Name of Partner\n(to encode in overview sheet)","Country\n(to encode in overview sheet)","Nature, type and specifications of the item","Amount\nExcluding VAT\n(EUR)","Total\n(EUR)","Check\nData\nEncoding"]
[]
[null,null,null,{"$f":"IFERROR(IF(VLOOKUP(C13,PartnerN°Ref,2,FALSE)=0,\"\",VLOOKUP(C13,PartnerN°Ref,2,FALSE)),\"\")","v":""},{"$f":"IFERROR(IF(OR(VLOOKUP(C13,PartnerN°Ref,4,FALSE)=\"Country not found\",VLOOKUP(C13,PartnerN°Ref,3,FALSE)=0),\"\",VLOOKUP(C13,PartnerN°Ref,3,FALSE)),\"\")","v":""},null,0,{"$f":"IF(I13=\"Error\",0,ROUND(G13,2))","v":0},{"$f":"IF(OR(COUNTIF(WorkPackage,B13)=0,COUNTIF(PartnerN°,C13)=0,D13=\"\",COUNTIF(CountryALL,E13)=0,F13=\"\",ISNUMBER(G13)=FALSE,IF(ISNUMBER(G13)=TRUE,G13=INT(G13*100)/100=FALSE)),\"Error\",\"\")","v":"Error"}]
[null,null,null,{"$f":"IFERROR(IF(VLOOKUP(C14,PartnerN°Ref,2,FALSE)=0,\"\",VLOOKUP(C14,PartnerN°Ref,2,FALSE)),\"\")","v":""},{"$f":"IFERROR(IF(OR(VLOOKUP(C14,PartnerN°Ref,4,FALSE)=\"Country not found\",VLOOKUP(C14,PartnerN°Ref,3,FALSE)=0),\"\",VLOOKUP(C14,PartnerN°Ref,3,FALSE)),\"\")","v":""},null,0,{"$f":"IF(I14=\"Error\",0,ROUND(G14,2))","v":0},{"$f":"IF(OR(COUNTIF(WorkPackage,B14)=0,COUNTIF(PartnerN°,C14)=0,D14=\"\",COUNTIF(CountryALL,E14)=0,F14=\"\",ISNUMBER(G14)=FALSE,IF(ISNUMBER(G14)=TRUE,G14=INT(G14*100)/100=FALSE)),\"Error\",\"\")","v":"Error"}]

{"sheet":"Co-financing","index":6,"n_rows":18,"n_cols":10,"rows_kept":18,"cut":false,"hidden":false,"merged":[[0,1,0,9],[2,1,2,9],[9,1,9,9],[10,9,11,9],[1,1,1,9],[10,8,11,8],[10,5,11,5],[3,2,8,2],[3,1,8,1],[10,1,11,1],[10,2,11,2],[10,3,11,3],[10,6,11,6],[10,7,11,7],[10,4,11,4],[3,3,8,9]]}
[]
[null,"Information for the Co-financing"]
[]
[null,"Total (EUR)",{"$f":"SUM(I:I)","v":0}]
[]
[]
[]
[]
[]
[]
[null,"Partner \nN°","Name of Partner\n(to encode in overview sheet)","Country\n(to encode in overview sheet)","Item*","Source of Co-financing**","Justification***","Amount\nExcluding VAT\n(EUR)","Total\n(EUR)","Check\nData\nEncoding"]
[]
[null,null,{"$f":"IFERROR(IF(VLOOKUP(B13,PartnerN°Ref,2,FALSE)=0,\"\",VLOOKUP(B13,PartnerN°Ref,2,FALSE)),\"\")","v":""},{"$f":"IFERROR(IF(OR(VLOOKUP(B13,PartnerN°Ref,4,FALSE)=\"Country not found\",VLOOKUP(B13,PartnerN°Ref,3,FALSE)=0),\"\",VLOOKUP(B13,PartnerN°Ref,3,FALSE)),\"\")","v":""},null,null,null,0,{"$f":"IF(J13=\"Error\",0,ROUND(H13,2))","v":0},{"$f":"IF(OR(COUNTIF(PartnerN°,B13)=0,C13=\"\",COUNTIF(CountryALL,D13)=0,E13=\"\",F13=\"\",G13=\"\",ISNUMBER(H13)=FALSE,IF(ISNUMBER(H13)=TRUE,H13=INT(H13*100)/100=FALSE)),\"Error\",\"\")","v":"Error"}]
[null,null,{"$f":"IFERROR(IF(VLOOKUP(B14,PartnerN°Ref,2,FALSE)=0,\"\",VLOOKUP(B14,PartnerN°Ref,2,FALSE)),\"\")","v":""},{"$f":"IFERROR(IF(OR(VLOOKUP(B14,PartnerN°Ref,4,FALSE)=\"Country not found\",VLOOKUP(B14,PartnerN°Ref,3,FALSE)=0),\"\",VLOOKUP(B14,PartnerN°Ref,3,FALSE)),\"\")","v":""},null,null,null,0,{"$f":"IF(J14=\"Error\",0,ROUND(H14,2))","v":0},{"$f":"IF(OR(COUNTIF(PartnerN°,B14)=0,C14=\"\",COUNTIF(CountryALL,D14)=0,E14=\"\",F14=\"\",G14=\"\",ISNUMBER(H14)=FALSE,IF(ISNUMBER(H14)=TRUE,H14=INT(H14*100)/100=FALSE)),\"Error\",\"\")","v":"Error"}]
[]
[null,"* e.g.: Equipment,  Staff costs, travel costs and/or costs of stay, printing & publishing"]
[null,"** e.g.: governmental grant, organisation/institution's own resources"]
[null,"*** e.g.: Preparation of training materials - 2 days x 7,5 hours x 3 persons x € 25"]

{"sheet":"Breakdown & Project Funding","index":7,"n_rows":77,"n_cols":9,"rows_kept":77,"cut":false,"hidden":false,"merged":[[19,1,19,8],[4,7,8,7],[0,1,0,8],[17,1,17,8],[12,1,12,8],[11,1,11,8],[18,1,18,8],[13,7,13,8],[14,7,14,8],[15,7,15,8],[16,7,16,8],[10,1,10,8],[2,1,2,8],[1,1,1,8]]}
[]
[null,"Budget Breakdown by Workpackage / Budget Headings"]
[]
[null,"Work\nPackage","1. Staff \nCosts","2. Travel \nCosts","3. Costs \nof Stay","4. Equipment\nCosts","5. Subcontracting\nCosts","a) Exceptional \nTravel Costs","Total\n(EUR)"]
[null,{"$f":"'Unit Costs & Funding Rule'!P10","v":"Preparation"},{"$f":"SUMIF('1. Staff costs'!B:B,B5,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!B:B,B5,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!B:B,B5,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!B:B,B5,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!B:B,B5,'5. Subcontracting Costs'!H:H)","v":0},null,{"$f":"SUM(C5:G5)","v":0}]
[null,{"$f":"'Unit Costs & Funding Rule'!P11","v":"Development"},{"$f":"SUMIF('1. Staff costs'!B:B,B6,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!B:B,B6,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!B:B,B6,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!B:B,B6,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!B:B,B6,'5. Subcontracting Costs'!H:H)","v":0},null,{"$f":"SUM(C6:G6)","v":0}]
[null,{"$f":"'Unit Costs & Funding Rule'!P12","v":"Quality Plan"},{"$f":"SUMIF('1. Staff costs'!B:B,B7,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!B:B,B7,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!B:B,B7,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!B:B,B7,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!B:B,B7,'5. Subcontracting Costs'!H:H)","v":0},null,0]
[null,{"$f":"'Unit Costs & Funding Rule'!P13","v":"Dissemination & Exploitation"},{"$f":"SUMIF('1. Staff costs'!B:B,B8,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!B:B,B8,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!B:B,B8,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!B:B,B8,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!B:B,B8,'5. Subcontracting Costs'!H:H)","v":0},null,0]
[null,{"$f":"'Unit Costs & Funding Rule'!P14","v":"Management"},{"$f":"SUMIF('1. Staff costs'!B:B,B9,'1. Staff costs'!S:S)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!B:B,B9,'2-3. Travel Costs&Costs of Stay'!L:L)","v":0},{"$f":"SUMIF('2-3. Travel Costs&Costs of Stay'!B:B,B9,'2-3. Travel Costs&Costs of Stay'!M:M)","v":0},{"$f":"SUMIF('4. Equipment Costs'!B:B,B9,'4. Equipment Costs'!H:H)","v":0},{"$f":"SUMIF('5. Subcontracting Costs'!B:B,B9,'5. Subcontracting Costs'!H:H)","v":0},null,0]
[null,"Total",{"$f":"SUM(C5:C9)","v":0},0,0,0,{"$f":"SUM(G5:G9)","v":0},{"$f":"IF(OR(Overview!C26=\"\",Overview!D26=\"\"),0,'2-3. Travel Costs&Costs of Stay'!J4)","v":0},{"$f":"SUM(C10:H10)","v":0}]
[]
[null,"Budget Breakdown by Programme or Partner Countries / Budget Headings"]
[]
[null,"Countries","1. Staff \nCosts","2. Travel \nCosts + Exceptional Travel Costs","3. Costs \nof Stay","4. Equipment\nCosts","5. Subcontracting\nCosts","Total\n(EUR)"]
[null,"Programme Countries",{"$f":"SUMIF(Overview!$E$26:$E$80,B15,Overview!$F$26:$F$80)","v":0},{"$f":"SUMIF(Overview!$E$26:$E$80,B15,Overview!$G$26:$G$80)","v":0},{"$f":"SUMIF(Overview!$E$26:$E$80,B15,Overview!$H$26:$H$80)","v":0},{"$f":"SUMIF(Overview!$E$26:$E$80,B15,Overview!$I$26:$I$80)","v":0},{"$f":"SUMIF(Overview!$E$26:$E$80,B15,Overview!$J$26:$J$80)","v":0},{"$f":"SUM(C15:G15)","v":0}]
[null,"Partner Countries",{"$f":"SUMIF(Overview!$E$26:$E$80,B16,Overview!$F$26:$F$80)","v":0},{"$f":"SUMIF(Overview!$E$26:$E$80,B16,Overview!$G$26:$G$80)","v":0},{"$f":"SUMIF(Overview!$E$26:$E$80,B16,Overview!$H$26:$H$80)","v":0},{"$f":"SUMIF(Overview!$E$26:$E$80,B16,Overview!$I$26:$I$80)","v":0},{"$f":"SUMIF(Overview!$E$26:$E$80,B16,Overview!$J$26:$J$80)","v":0},{"$f":"SUM(C16:G16)","v":0}]
[null,"Total",{"$f":"SUM(C15:C16)","v":0},0,0,0,0,{"$f":"SUM(C17:G17)","v":0}]
[]
[null,"Budget Breakdown by Partner / Work Package"]
[]
[null,"Partner\nN°",{"$f":"'Unit Costs & Funding Rule'!P10","v":"Preparation"},{"$f":"'Unit Costs & Funding Rule'!P11","v":"Development"},{"$f":"'Unit Costs & Funding Rule'!P12","v":"Quality Plan"},{"$f":"'Unit Costs & Funding Rule'!P13","v":"Dissemination & Exploitation"},{"$f":"'Unit Costs & Funding Rule'!P14","v":"Management"},"a) Exceptional \nTravel Costs","Total\n(EUR)"]
[null,"P1",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B22,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B22,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B22,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B22,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B22,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B22,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B22,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B22,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B22,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B22,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B22,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B22,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B22,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B22,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B22,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B22,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B22,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B22,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B22,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B22,'5. Subcontracting Costs'!B:B,$G$21)","v":0},{"$f":"IF(OR(Overview!C26=\"\",Overview!D26=\"\"),0,'2-3. Travel Costs&Costs of Stay'!J4)","v":0},{"$f":"SUM(C22:H22)","v":0}]
[null,"P2",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B23,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B23,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B23,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B23,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B23,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B23,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B23,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B23,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B23,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B23,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B23,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B23,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B23,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B23,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B23,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B23,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B23,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B23,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B23,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B23,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,{"$f":"SUM(C23:H23)","v":0}]
[null,"P3",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B24,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B24,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B24,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B24,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B24,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B24,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B24,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B24,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B24,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B24,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B24,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B24,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B24,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B24,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B24,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B24,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B24,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B24,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B24,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B24,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P4",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B25,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B25,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B25,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B25,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B25,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B25,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B25,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B25,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B25,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B25,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B25,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B25,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B25,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B25,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B25,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B25,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B25,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B25,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B25,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B25,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P5",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B26,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B26,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B26,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B26,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B26,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B26,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B26,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B26,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B26,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B26,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B26,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B26,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B26,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B26,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B26,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B26,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B26,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B26,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B26,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B26,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P6",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B27,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B27,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B27,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B27,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B27,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B27,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B27,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B27,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B27,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B27,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B27,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B27,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B27,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B27,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B27,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B27,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B27,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B27,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B27,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B27,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P7",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B28,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B28,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B28,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B28,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B28,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B28,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B28,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B28,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B28,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B28,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B28,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B28,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B28,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B28,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B28,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B28,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B28,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B28,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B28,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B28,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P8",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B29,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B29,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B29,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B29,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B29,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B29,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B29,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B29,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B29,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B29,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B29,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B29,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B29,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B29,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B29,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B29,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B29,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B29,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B29,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B29,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P9",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B30,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B30,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B30,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B30,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B30,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B30,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B30,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B30,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B30,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B30,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B30,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B30,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B30,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B30,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B30,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B30,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B30,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B30,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B30,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B30,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P10",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B31,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B31,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B31,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B31,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B31,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B31,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B31,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B31,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B31,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B31,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B31,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B31,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B31,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B31,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B31,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B31,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B31,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B31,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B31,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B31,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P11",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B32,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B32,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B32,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B32,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B32,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B32,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B32,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B32,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B32,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B32,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B32,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B32,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B32,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B32,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B32,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B32,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B32,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B32,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B32,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B32,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P12",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B33,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B33,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B33,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B33,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B33,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B33,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B33,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B33,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B33,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B33,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B33,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B33,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B33,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B33,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B33,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B33,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B33,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B33,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B33,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B33,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P13",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B34,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B34,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B34,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B34,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B34,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B34,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B34,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B34,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B34,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B34,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B34,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B34,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B34,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B34,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B34,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B34,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B34,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B34,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B34,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B34,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P14",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B35,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B35,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B35,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B35,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B35,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B35,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B35,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B35,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B35,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B35,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B35,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B35,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B35,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B35,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B35,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B35,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B35,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B35,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B35,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B35,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P15",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B36,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B36,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B36,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B36,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B36,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B36,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B36,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B36,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B36,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B36,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B36,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B36,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B36,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B36,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B36,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B36,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B36,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B36,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B36,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B36,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P16",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B37,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B37,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B37,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B37,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B37,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B37,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B37,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B37,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B37,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B37,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B37,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B37,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B37,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B37,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B37,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B37,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B37,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B37,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B37,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B37,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P17",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B38,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B38,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B38,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B38,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B38,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B38,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B38,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B38,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B38,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B38,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B38,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B38,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B38,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B38,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B38,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B38,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B38,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B38,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B38,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B38,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P18",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B39,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B39,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B39,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B39,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B39,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B39,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B39,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B39,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B39,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B39,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B39,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B39,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B39,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B39,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B39,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B39,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B39,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B39,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B39,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B39,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P19",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B40,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B40,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B40,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B40,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B40,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B40,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B40,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B40,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B40,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B40,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B40,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B40,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B40,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B40,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B40,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B40,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B40,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B40,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B40,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B40,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P20",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B41,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B41,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B41,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B41,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B41,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B41,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B41,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B41,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B41,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B41,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B41,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B41,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B41,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B41,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B41,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B41,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B41,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B41,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B41,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B41,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P21",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B42,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B42,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B42,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B42,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B42,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B42,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B42,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B42,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B42,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B42,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B42,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B42,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B42,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B42,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B42,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B42,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B42,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B42,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B42,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B42,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P22",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B43,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B43,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B43,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B43,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B43,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B43,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B43,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B43,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B43,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B43,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B43,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B43,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B43,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B43,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B43,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B43,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B43,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B43,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B43,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B43,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P23",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B44,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B44,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B44,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B44,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B44,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B44,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B44,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B44,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B44,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B44,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B44,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B44,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B44,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B44,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B44,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B44,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B44,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B44,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B44,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B44,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P24",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B45,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B45,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B45,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B45,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B45,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B45,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B45,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B45,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B45,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B45,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B45,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B45,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B45,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B45,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B45,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B45,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B45,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B45,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B45,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B45,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P25",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B46,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B46,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B46,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B46,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B46,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B46,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B46,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B46,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B46,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B46,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B46,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B46,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B46,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B46,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B46,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B46,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B46,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B46,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B46,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B46,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P26",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B47,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B47,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B47,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B47,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B47,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B47,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B47,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B47,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B47,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B47,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B47,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B47,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B47,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B47,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B47,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B47,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B47,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B47,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B47,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B47,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P27",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B48,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B48,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B48,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B48,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B48,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B48,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B48,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B48,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B48,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B48,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B48,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B48,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B48,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B48,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B48,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B48,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B48,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B48,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B48,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B48,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P28",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B49,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B49,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B49,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B49,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B49,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B49,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B49,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B49,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B49,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B49,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B49,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B49,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B49,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B49,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B49,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B49,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B49,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B49,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B49,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B49,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P29",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B50,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B50,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B50,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B50,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B50,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B50,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B50,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B50,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B50,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B50,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B50,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B50,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B50,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B50,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B50,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B50,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B50,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B50,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B50,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B50,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P30",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B51,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B51,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B51,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B51,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B51,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B51,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B51,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B51,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B51,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B51,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B51,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B51,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B51,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B51,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B51,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B51,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B51,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B51,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B51,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B51,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P31",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B52,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B52,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B52,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B52,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B52,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B52,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B52,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B52,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B52,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B52,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B52,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B52,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B52,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B52,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B52,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B52,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B52,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B52,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B52,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B52,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P32",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B53,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B53,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B53,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B53,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B53,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B53,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B53,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B53,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B53,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B53,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B53,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B53,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B53,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B53,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B53,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B53,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B53,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B53,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B53,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B53,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P33",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B54,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B54,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B54,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B54,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B54,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B54,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B54,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B54,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B54,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B54,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B54,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B54,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B54,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B54,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B54,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B54,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B54,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B54,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B54,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B54,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P34",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B55,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B55,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B55,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B55,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B55,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B55,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B55,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B55,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B55,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B55,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B55,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B55,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B55,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B55,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B55,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B55,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B55,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B55,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B55,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B55,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P35",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B56,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B56,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B56,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B56,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B56,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B56,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B56,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B56,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B56,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B56,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B56,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B56,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B56,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B56,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B56,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B56,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B56,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B56,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B56,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B56,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P36",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B57,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B57,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B57,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B57,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B57,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B57,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B57,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B57,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B57,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B57,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B57,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B57,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B57,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B57,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B57,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B57,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B57,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B57,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B57,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B57,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P37",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B58,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B58,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B58,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B58,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B58,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B58,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B58,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B58,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B58,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B58,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B58,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B58,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B58,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B58,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B58,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B58,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B58,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B58,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B58,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B58,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P38",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B59,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B59,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B59,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B59,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B59,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B59,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B59,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B59,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B59,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B59,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B59,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B59,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B59,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B59,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B59,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B59,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B59,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B59,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B59,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B59,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P39",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B60,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B60,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B60,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B60,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B60,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B60,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B60,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B60,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B60,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B60,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B60,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B60,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B60,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B60,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B60,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B60,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B60,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B60,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B60,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B60,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P40",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B61,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B61,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B61,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B61,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B61,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B61,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B61,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B61,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B61,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B61,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B61,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B61,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B61,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B61,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B61,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B61,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B61,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B61,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B61,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B61,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P41",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B62,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B62,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B62,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B62,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B62,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B62,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B62,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B62,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B62,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B62,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B62,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B62,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B62,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B62,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B62,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B62,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B62,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B62,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B62,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B62,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P42",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B63,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B63,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B63,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B63,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B63,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B63,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B63,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B63,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B63,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B63,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B63,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B63,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B63,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B63,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B63,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B63,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B63,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B63,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B63,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B63,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P43",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B64,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B64,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B64,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B64,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B64,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B64,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B64,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B64,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B64,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B64,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B64,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B64,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B64,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B64,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B64,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B64,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B64,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B64,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B64,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B64,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P44",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B65,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B65,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B65,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B65,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B65,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B65,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B65,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B65,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B65,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B65,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B65,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B65,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B65,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B65,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B65,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B65,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B65,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B65,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B65,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B65,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P45",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B66,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B66,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B66,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B66,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B66,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B66,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B66,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B66,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B66,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B66,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B66,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B66,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B66,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B66,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B66,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B66,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B66,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B66,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B66,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B66,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P46",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B67,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B67,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B67,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B67,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B67,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B67,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B67,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B67,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B67,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B67,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B67,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B67,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B67,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B67,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B67,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B67,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B67,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B67,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B67,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B67,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P47",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B68,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B68,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B68,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B68,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B68,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B68,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B68,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B68,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B68,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B68,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B68,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B68,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B68,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B68,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B68,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B68,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B68,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B68,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B68,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B68,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P48",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B69,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B69,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B69,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B69,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B69,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B69,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B69,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B69,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B69,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B69,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B69,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B69,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B69,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B69,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B69,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B69,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B69,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B69,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B69,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B69,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P49",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B70,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B70,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B70,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B70,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B70,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B70,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B70,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B70,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B70,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B70,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B70,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B70,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B70,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B70,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B70,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B70,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B70,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B70,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B70,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B70,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P50",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B71,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B71,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B71,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B71,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B71,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B71,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B71,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B71,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B71,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B71,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B71,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B71,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B71,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B71,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B71,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B71,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B71,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B71,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B71,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B71,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P51",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B72,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B72,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B72,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B72,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B72,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B72,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B72,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B72,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B72,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B72,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B72,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B72,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B72,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B72,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B72,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B72,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B72,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B72,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B72,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B72,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P52",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B73,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B73,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B73,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B73,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B73,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B73,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B73,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B73,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B73,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B73,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B73,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B73,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B73,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B73,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B73,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B73,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B73,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B73,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B73,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B73,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P53",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B74,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B74,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B74,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B74,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B74,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B74,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B74,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B74,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B74,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B74,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B74,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B74,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B74,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B74,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B74,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B74,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B74,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B74,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B74,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B74,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P54",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B75,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B75,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B75,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B75,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B75,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B75,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B75,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B75,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B75,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B75,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B75,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B75,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B75,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B75,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B75,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B75,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B75,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B75,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B75,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B75,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"P55",{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B76,'1. Staff costs'!B:B,$C$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B76,'2-3. Travel Costs&Costs of Stay'!B:B,$C$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B76,'4. Equipment Costs'!B:B,$C$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B76,'5. Subcontracting Costs'!B:B,$C$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B76,'1. Staff costs'!B:B,$D$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B76,'2-3. Travel Costs&Costs of Stay'!B:B,$D$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B76,'4. Equipment Costs'!B:B,$D$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B76,'5. Subcontracting Costs'!B:B,$D$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B76,'1. Staff costs'!B:B,$E$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B76,'2-3. Travel Costs&Costs of Stay'!B:B,$E$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B76,'4. Equipment Costs'!B:B,$E$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B76,'5. Subcontracting Costs'!B:B,$E$21)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B76,'1. Staff costs'!B:B,$B$8)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B76,'2-3. Travel Costs&Costs of Stay'!B:B,$B$8)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B76,'4. Equipment Costs'!B:B,$B$8)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B76,'5. Subcontracting Costs'!B:B,$B$8)","v":0},{"$f":"SUMIFS('1. Staff costs'!S:S,'1. Staff costs'!C:C,B76,'1. Staff costs'!B:B,$G$21)+SUMIFS('2-3. Travel Costs&Costs of Stay'!N:N,'2-3. Travel Costs&Costs of Stay'!C:C,B76,'2-3. Travel Costs&Costs of Stay'!B:B,$G$21)+SUMIFS('4. Equipment Costs'!H:H,'4. Equipment Costs'!C:C,B76,'4. Equipment Costs'!B:B,$G$21)+SUMIFS('5. Subcontracting Costs'!H:H,'5. Subcontracting Costs'!C:C,B76,'5. Subcontracting Costs'!B:B,$G$21)","v":0},0,0]
[null,"Total",{"$f":"SUM(C22:C76)","v":0},{"$f":"SUM(D22:D76)","v":0},0,0,0,{"$f":"SUM(H22:H76)","v":0},{"$f":"SUM(C77:H77)","v":0}]

{"sheet":"Unit Costs & Funding Rule","index":8,"n_rows":186,"n_cols":19,"rows_kept":186,"cut":false,"hidden":false,"merged":[[6,15,6,16],[6,18,6,20],[4,1,5,6],[4,8,5,9],[4,11,5,13],[4,15,5,16],[4,18,5,20],[0,1,0,20],[3,1,3,6],[3,8,3,9],[3,11,3,13],[3,15,3,16],[3,18,3,20]]}
[null,"UNIT COSTS AND SUMMARY OF THE FUNDING RULES FOR  JOINT AND STRUCTURAL CAPACITY BUILDING PROJECTS\n\nYou can find below the unit costs values used in this file for the calculation of the grant.\nPlease refer to the Erasmus+ Programme guide 2017* for a complete overview of the funding rules applying to the Joint and Structural Capacity Building Projects (Part B of the guide and Annex 1)."]
[null,"* Link to Erasmus+ Programme guide 2018: ","https://ec.europa.eu/programmes/erasmus-plus/sites/erasmusplus2/files/files/resources/erasmus-plus-programme-guide_en.pdf"]
[null,"* Link to CBHE Call for proposal, forms, annexes and guidelines: ","https://eacea.ec.europa.eu/erasmus-plus/funding/capacity-building-higher-education-2018_en"]
[null,"A.1 Staff Costs",null,null,null,null,null,null,"A.2 & B Travel Costs",null,null,"A. 3 Costs of Stay",null,null,null,"A.4 Equipment",null,null,"A.5 Subcontracting"]
[null,"Unit costs\n\nContribution to the costs of staff performing tasks which are directly necessary to the achievements of the project's objectives.\n\nConditional: applicants will have to justify the type and volume of resources needed in relation to the implementation of the proposed activities and outputs. The contribution is provided on the  condition that the salary for the same tasks is compensated only once.",null,null,null,null,null,null,"Unit costs based on the travel distance per participant. \n\nTravel distances must be calculated using the distance calculator supported by the European Commission . \nThe applicant must indicate the distance of a one-way travel to calculate the amount of the EU grant that will support the round trip.",null,null,"Costs for subsistence, accommodation, local and public transport such as bus and taxi, personal or optional health insurance.\n\nUnit costs based on the duration of the stay of the participants:\n\nStaff: \n120 EUR/day from day 1 to day 14\n70 EUR/day from day 15 to day 60\n50 EUR/day from day 61 to day 90 (the maximum)\n\nStudent: \n55 EUR/day from day 1 to day 14\n40 EUR/day from day 15 to max day 90 (the maximum)",null,null,null,"Contribution for the purchase of equipment necessary for the implementation of the project. Support is provided only for equipment purchased for the benefit of the HEIs in the Partner Countries. \n\nConditional: the request for financial support to cover these costs must be motivated in the application form",null,null,"Support for sub-contracting costs that are necessary to the implementation of the project, including, in particular, costs for the compulsory financial audits (audit certificate) and for any external quality assurance procedure.\n\nSub-contracting for project-management-related tasks is not eligible.\n\nSub-contracting to external bodies should be very occasional. The specific competences and particular expertise needed to reach the project objectives should be found in the consortium and should determine its composition."]
[]
[null,"Country","PR/PA","Manager","Teacher/Trainer/Researcher","Technical Staff","Administrative Staff",null,"Distance","Travel \nCosts\n(EUR)",null,"Number of \nDays","Student","Staff",null,"100% of eligible costs\nMax. 30% of the total grant",null,null,"100% of eligible costs\nMax. 10% of the total grant"]
[null,"Austria","Programme Countries",294,241,190,157,null,"0 KM and 9 KM",0,null,1,{"$f":"L8*55","v":55},{"$f":"L8*120","v":120}]
[null,"Belgium","Programme Countries",280,214,162,131,null,"10 KM and 99 KM",20,null,2,{"$f":"L9*55","v":110},{"$f":"L9*120","v":240},null,"WorkPackage"]
[null,"Bulgaria","Programme Countries",88,74,55,39,null,"100 KM and 499 KM",180,null,3,165,360,null,"Preparation"]
[null,"Croatia","Programme Countries",88,74,55,39,null,"500 KM and 1999 KM",275,null,4,220,480,null,"Development"]
[null,"Cyprus","Programme Countries",164,137,102,78,null,"2000 KM and 2999 KM",360,null,5,275,600,null,"Quality Plan"]
[null,"Czech Republic","Programme Countries",164,137,102,78,null,"3000 KM and 3999 KM",530,null,6,330,720,null,"Dissemination & Exploitation"]
[null,"Denmark","Programme Countries",294,241,190,157,null,"4000 KM and 7999 KM",820,null,7,385,840,null,"Management"]
[null,"Estonia","Programme Countries",88,74,55,39,null,"8000 KM or more",1500,null,8,440,960]
[null,"Finland","Programme Countries",280,214,162,131,null,null,null,null,9,495,1080,null,"Category"]
[null,"former Yugoslav Republic of Macedonia","Programme Countries",88,74,55,39,null,null,null,null,10,550,1200,null,"Staff"]
[null,"France","Programme Countries",280,214,162,131,null,null,null,null,11,605,1320,null,"Student"]
[null,"Germany","Programme Countries",280,214,162,131,null,null,null,null,12,660,1440]
[null,"Greece","Programme Countries",164,137,102,78,null,null,null,null,13,715,1560]
[null,"Hungary","Programme Countries",88,74,55,39,null,null,null,null,14,770,1680]
[null,"Iceland","Programme Countries",280,214,162,131,null,null,null,null,15,{"$f":"((L22-$L$21)*40)+770","v":810},{"$f":"((L22-$L$21)*70)+1680","v":1750}]
[null,"Ireland","Programme Countries",294,241,190,157,null,null,null,null,16,{"$f":"((L23-$L$21)*40)+770","v":850},{"$f":"((L23-$L$21)*70)+1680","v":1820}]
[null,"Italy","Programme Countries",280,214,162,131,null,null,null,null,17,890,1890]
[null,"Latvia","Programme Countries",88,74,55,39,null,null,null,null,18,930,1960]
[null,"Liechtenstein","Programme Countries",294,241,190,157,null,null,null,null,19,970,2030]
[null,"Lithuania","Programme Countries",88,74,55,39,null,null,null,null,20,1010,2100]
[null,"Luxembourg","Programme Countries",294,241,190,157,null,null,null,null,21,1050,2170]
[null,"Malta","Programme Countries",164,137,102,78,null,null,null,null,22,1090,2240]
[null,"Netherlands","Programme Countries",294,241,190,157,null,null,null,null,23,1130,2310]
[null,"Norway","Programme Countries",294,241,190,157,null,null,null,null,24,1170,2380]
[null,"Poland","Programme Countries",88,74,55,39,null,null,null,null,25,1210,2450]
[null,"Portugal","Programme Countries",164,137,102,78,null,null,null,null,26,1250,2520]
[null,"Romania","Programme Countries",88,74,55,39,null,null,null,null,27,1290,2590]
[null,"Slovakia","Programme Countries",88,74,55,39,null,null,null,null,28,1330,2660]
[null,"Slovenia","Programme Countries",164,137,102,78,null,null,null,null,29,1370,2730]
[null,"Spain","Programme Countries",164,137,102,78,null,null,null,null,30,1410,2800]
[null,"Sweden","Programme Countries",294,241,190,157,null,null,null,null,31,1450,2870]
[null,"Turkey","Programme Countries",88,74,55,39,null,null,null,null,32,1490,2940]
[null,"United Kingdom","Programme Countries",280,214,162,131,null,null,null,null,33,1530,3010]
[null,"Afghanistan","Partner Countries",77,57,40,32,null,null,null,null,34,1570,3080]
[null,"Albania","Partner Countries",108,80,57,45,null,null,null,null,35,1610,3150]
[null,"Algeria","Partner Countries",47,33,22,17,null,null,null,null,36,1650,3220]
[null,"Angola","Partner Countries",108,80,57,45,null,null,null,null,37,1690,3290]
[null,"Antigua and Barbuda","Partner Countries",108,80,57,45,null,null,null,null,38,1730,3360]
[null,"Argentina","Partner Countries",108,80,57,45,null,null,null,null,39,1770,3430]
[null,"Armenia","Partner Countries",47,33,22,17,null,null,null,null,40,1810,3500]
[null,"Azerbaijan","Partner Countries",77,57,40,32,null,null,null,null,41,1850,3570]
[null,"Bahamas","Partner Countries",77,57,40,32,null,null,null,null,42,1890,3640]
[null,"Bangladesh","Partner Countries",47,33,22,17,null,null,null,null,43,1930,3710]
[null,"Barbados","Partner Countries",108,80,57,45,null,null,null,null,44,1970,3780]
[null,"Belarus","Partner Countries",47,33,22,17,null,null,null,null,45,2010,3850]
[null,"Belize","Partner Countries",47,33,22,17,null,null,null,null,46,2050,3920]
[null,"Benin","Partner Countries",47,33,22,17,null,null,null,null,47,2090,3990]
[null,"Bhutan","Partner Countries",47,33,22,17,null,null,null,null,48,2130,4060]
[null,"Bolivia","Partner Countries",77,57,40,32,null,null,null,null,49,2170,4130]
[null,"Bosnia and Herzegovina","Partner Countries",108,80,57,45,null,null,null,null,50,2210,4200]
[null,"Botswana","Partner Countries",47,33,22,17,null,null,null,null,51,2250,4270]
[null,"Brazil","Partner Countries",108,80,57,45,null,null,null,null,52,2290,4340]
[null,"Burkina Faso","Partner Countries",77,57,40,32,null,null,null,null,53,2330,4410]
[null,"Burundi","Partner Countries",47,33,22,17,null,null,null,null,54,2370,4480]
[null,"Cambodia","Partner Countries",47,33,22,17,null,null,null,null,55,2410,4550]
[null,"Cameroon","Partner Countries",77,57,40,32,null,null,null,null,56,2450,4620]
[null,"Cape Verde","Partner Countries",47,33,22,17,null,null,null,null,57,2490,4690]
[null,"Central African Republic","Partner Countries",47,33,22,17,null,null,null,null,58,2530,4760]
[null,"Chad","Partner Countries",47,33,22,17,null,null,null,null,59,2570,4830]
[null,"Chile","Partner Countries",108,80,57,45,null,null,null,null,60,2610,4900]
[null,"China","Partner Countries",77,57,40,32,null,null,null,null,61,2650,{"$f":"((L68-$L$67)*50)+4900","v":4950}]
[null,"Colombia","Partner Countries",108,80,57,45,null,null,null,null,62,2690,{"$f":"((L69-$L$67)*50)+4900","v":5000}]
[null,"Comoros","Partner Countries",108,80,57,45,null,null,null,null,63,2730,5050]
[null,"Congo","Partner Countries",77,57,40,32,null,null,null,null,64,2770,5100]
[null,"Congo - Republic of the-","Partner Countries",47,33,22,17,null,null,null,null,65,2810,5150]
[null,"Cook Islands","Partner Countries",108,80,57,45,null,null,null,null,66,2850,5200]
[null,"Costa Rica","Partner Countries",77,57,40,32,null,null,null,null,67,2890,5250]
[null,"Cuba","Partner Countries",47,33,22,17,null,null,null,null,68,2930,5300]
[null,"Djibouti","Partner Countries",77,57,40,32,null,null,null,null,69,2970,5350]
[null,"Dominica","Partner Countries",108,80,57,45,null,null,null,null,70,3010,5400]
[null,"Dominican Republic","Partner Countries",77,57,40,32,null,null,null,null,71,3050,5450]
[null,"DPR Korea","Partner Countries",47,33,22,17,null,null,null,null,72,3090,5500]
[null,"Ecuador","Partner Countries",77,57,40,32,null,null,null,null,73,3130,5550]
[null,"Egypt","Partner Countries",47,33,22,17,null,null,null,null,74,3170,5600]
[null,"El Salvador","Partner Countries",77,57,40,32,null,null,null,null,75,3210,5650]
[null,"Equatorial Guinea","Partner Countries",47,33,22,17,null,null,null,null,76,3250,5700]
[null,"Eritrea","Partner Countries",47,33,22,17,null,null,null,null,77,3290,5750]
[null,"Ethiopia","Partner Countries",47,33,22,17,null,null,null,null,78,3330,5800]
[null,"Fiji","Partner Countries",47,33,22,17,null,null,null,null,79,3370,5850]
[null,"Gabon","Partner Countries",108,80,57,45,null,null,null,null,80,{"$f":"((L87-$L$21)*40)+770","v":3410},5900]
[null,"Gambia","Partner Countries",47,33,22,17,null,null,null,null,81,3450,5950]
[null,"Georgia","Partner Countries",77,57,40,32,null,null,null,null,82,3490,6000]
[null,"Ghana","Partner Countries",47,33,22,17,null,null,null,null,83,3530,6050]
[null,"Grenada","Partner Countries",108,80,57,45,null,null,null,null,84,3570,6100]
[null,"Guatemala","Partner Countries",77,57,40,32,null,null,null,null,85,3610,6150]
[null,"Guinea","Partner Countries",47,33,22,17,null,null,null,null,86,3650,6200]
[null,"Guinea-Bissau","Partner Countries",77,57,40,32,null,null,null,null,87,3690,6250]
[null,"Guyana","Partner Countries",47,33,22,17,null,null,null,null,88,3730,6300]
[null,"Haiti","Partner Countries",77,57,40,32,null,null,null,null,89,3770,6350]
[null,"Honduras","Partner Countries",47,33,22,17,null,null,null,null,90,3810,6400]
[null,"India","Partner Countries",47,33,22,17]
[null,"Indonesia","Partner Countries",47,33,22,17]
[null,"Iran","Partner Countries",77,57,40,32]
[null,"Iraq","Partner Countries",77,57,40,32]
[null,"Israel","Partner Countries",166,132,102,92]
[null,"Ivory Coast","Partner Countries",108,80,57,45]
[null,"Jamaica","Partner Countries",77,57,40,32]
[null,"Jordan","Partner Countries",77,57,40,32]
[null,"Kazakstan","Partner Countries",77,57,40,32]
[null,"Kenya","Partner Countries",77,57,40,32]
[null,"Kiribati","Partner Countries",47,33,22,17]
[null,"Kosovo","Partner Countries",108,80,57,45]
[null,"Kyrgyzstan","Partner Countries",47,33,22,17]
[null,"Laos","Partner Countries",47,33,22,17]
[null,"Lebanon","Partner Countries",108,80,57,45]
[null,"Lesotho","Partner Countries",47,33,22,17]
[null,"Liberia","Partner Countries",47,33,22,17]
[null,"Libya","Partner Countries",108,80,57,45]
[null,"Madagascar","Partner Countries",47,33,22,17]
[null,"Malawi","Partner Countries",47,33,22,17]
[null,"Malaysia","Partner Countries",47,33,22,17]
[null,"Maldives","Partner Countries",47,33,22,17]
[null,"Mali","Partner Countries",47,33,22,17]
[null,"Marshall Islands","Partner Countries",47,33,22,17]
[null,"Mauritania","Partner Countries",47,33,22,17]
[null,"Mauritius","Partner Countries",47,33,22,17]
[null,"Mexico","Partner Countries",108,80,57,45]
[null,"Micronesia - Federated States of-","Partner Countries",77,57,40,32]
[null,"Moldova","Partner Countries",47,33,22,17]
[null,"Mongolia","Partner Countries",47,33,22,17]
[null,"Montenegro","Partner Countries",108,80,57,45]
[null,"Morocco","Partner Countries",77,57,40,32]
[null,"Mozambique","Partner Countries",77,57,40,32]
[null,"Myanmar","Partner Countries",47,33,22,17]
[null,"Namibia","Partner Countries",77,57,40,32]
[null,"Nauru","Partner Countries",47,33,22,17]
[null,"Nepal","Partner Countries",47,33,22,17]
[null,"Nicaragua","Partner Countries",47,33,22,17]
[null,"Niger","Partner Countries",47,33,22,17]
[null,"Nigeria","Partner Countries",108,80,57,45]
[null,"Niue","Partner Countries",47,33,22,17]
[null,"Pakistan","Partner Countries",47,33,22,17]
[null,"Palau","Partner Countries",47,33,22,17]
[null,"Palestine","Partner Countries",77,57,40,32]
[null,"Panama","Partner Countries",77,57,40,32]
[null,"Papua New Guinea","Partner Countries",77,57,40,32]
[null,"Paraguay","Partner Countries",77,57,40,32]
[null,"Peru","Partner Countries",108,80,57,45]
[null,"Philippines","Partner Countries",47,33,22,17]
[null,"Russia","Partner Countries",77,57,40,32]
[null,"Rwanda","Partner Countries",47,33,22,17]
[null,"Saint Kitts and Nevis","Partner Countries",108,80,57,45]
[null,"Saint Lucia","Partner Countries",108,80,57,45]
[null,"Saint Vincent and the Grenadines","Partner Countries",108,80,57,45]
[null,"Samoa","Partner Countries",47,33,22,17]
[null,"Sao Tome and Principe","Partner Countries",108,80,57,45]
[null,"Senegal","Partner Countries",77,57,40,32]
[null,"Serbia","Partner Countries",108,80,57,45]
[null,"Seychelles","Partner Countries",108,80,57,45]
[null,"Sierra Leone","Partner Countries",47,33,22,17]
[null,"Solomon Islands","Partner Countries",47,33,22,17]
[null,"Somalia","Partner Countries",47,33,22,17]
[null,"South Africa","Partner Countries",77,57,40,32]
[null,"South Sudan","Partner Countries",47,33,22,17]
[null,"Sri Lanka","Partner Countries",47,33,22,17]
[null,"Sudan","Partner Countries",47,33,22,17]
[null,"Suriname","Partner Countries",77,57,40,32]
[null,"Swaziland","Partner Countries",77,57,40,32]
[null,"Syria","Partner Countries",47,33,22,17]
[null,"Tajikistan","Partner Countries",47,33,22,17]
[null,"Tanzania","Partner Countries",47,33,22,17]
[null,"Thailand","Partner Countries",108,80,57,45]
[null,"Timor Leste - Republic of-","Partner Countries",47,33,22,17]
[null,"Togo","Partner Countries",47,33,22,17]
[null,"Tonga","Partner Countries",47,33,22,17]
[null,"Trinidad and Tobago","Partner Countries",77,57,40,32]
[null,"Tunisia","Partner Countries",47,33,22,17]
[null,"Turkmenistan","Partner Countries",47,33,22,17]
[null,"Tuvalu","Partner Countries",47,33,22,17]
[null,"Uganda","Partner Countries",47,33,22,17]
[null,"Ukraine","Partner Countries",108,80,57,45]
[null,"Uruguay","Partner Countries",108,80,57,45]
[null,"Uzbekistan","Partner Countries",47,33,22,17]
[null,"Vanuatu","Partner Countries",77,57,40,32]
[null,"Venezuela","Partner Countries",108,80,57,45]
[null,"Vietnam","Partner Countries",47,33,22,17]
[null,"Yemen","Partner Countries",47,33,22,17]
[null,"Zambia","Partner Countries",108,80,57,45]
[null,"Zimbabwe","Partner Countries",108,80,57,45]